{"id":10508,"date":"2023-10-21T09:25:08","date_gmt":"2023-10-21T07:25:08","guid":{"rendered":"https:\/\/albapcb.com\/?p=10508"},"modified":"2023-10-24T09:01:31","modified_gmt":"2023-10-24T07:01:31","slug":"microtaladrado","status":"publish","type":"post","link":"https:\/\/albapcb.com\/es\/microtaladrado\/","title":{"rendered":"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite"},"content":{"rendered":"<p>En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12 taladradoras autom\u00e1ticas ya en funcionamiento.<\/p>\n<p>Nuestro constante af\u00e1n de innovaci\u00f3n nos permite garantizar un rendimiento excepcional para satisfacer la creciente demanda de circuitos multicapa cada vez m\u00e1s complejos, sofisticados y miniaturizados.<\/p>\n<p>Pluritec EVO2s gestiona autom\u00e1ticamente todo el proceso, desde la carga de paneles, con reconocimiento de c\u00f3digos de barras y gesti\u00f3n aut\u00f3noma del programa de taladrado, hasta la descarga final, todo ello a muy alta velocidad. Utiliza tres ejes independientes con motores lineales de gran estabilidad y dos electromandriles dise\u00f1ados para obtener el mejor resultado en funci\u00f3n del tipo de taladrado:<br \/>\n\u2022 uno dedicado a la microperforaci\u00f3n, que alcanza las 200.000 rpm.<br \/>\n\u2022 uno espec\u00edfico para el taladrado de grandes di\u00e1metros con una velocidad m\u00e1xima de 60.000 rpm.<\/p>\n<p>El ciclo de trabajo se caracteriza por su alta precisi\u00f3n: sistema \u00f3ptico para el centrado optimizado del taladrado incluso en placas de circuito impreso multicapa, control l\u00e1ser del di\u00e1metro de taladrado, ajuste de la profundidad del eje Z.<br \/>\nTodo ello con los l\u00edmites de producci\u00f3n llevados al m\u00e1ximo:<br \/>\n\u2022 Microtaladrado de hasta 0,1 mm.<br \/>\n\u2022 Taladrado con una tolerancia controlada de +\/-15 micras.<\/p>\n<p>En resumen, ofrecemos un taladrado de velocidad superior y resultados perfectos para garantizar a nuestros clientes la m\u00e1xima calidad y un servicio extremadamente r\u00e1pido.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12 taladradoras autom\u00e1ticas ya en funcionamiento. Nuestro constante af\u00e1n de innovaci\u00f3n nos permite garantizar un rendimiento excepcional para satisfacer la creciente demanda de circuitos multicapa cada vez m\u00e1s complejos, sofisticados y miniaturizados. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10561,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-10508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite - ALBA PCB Group<\/title>\n<meta name=\"description\" content=\"En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/albapcb.com\/es\/microtaladrado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite - ALBA PCB Group\" \/>\n<meta property=\"og:description\" content=\"En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12\" \/>\n<meta property=\"og:url\" content=\"https:\/\/albapcb.com\/es\/microtaladrado\/\" \/>\n<meta property=\"og:site_name\" content=\"ALBA PCB Group\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-21T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T07:01:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/Pluritec-EVO2s-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1108\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@albapcb_com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\"},\"headline\":\"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite\",\"datePublished\":\"2023-10-21T07:25:08+00:00\",\"dateModified\":\"2023-10-24T07:01:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/\"},\"wordCount\":257,\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/\",\"name\":\"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite - ALBA PCB Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"datePublished\":\"2023-10-21T07:25:08+00:00\",\"dateModified\":\"2023-10-24T07:01:31+00:00\",\"description\":\"En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Microforatura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/microtaladrado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/albapcb.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/albapcb.com\\\/es\\\/\",\"name\":\"ALBA PCB Group\",\"description\":\"Produttori di circuiti stampati di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/albapcb.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#organization\",\"name\":\"ALBA PCB\",\"url\":\"https:\\\/\\\/albapcb.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"width\":200,\"height\":229,\"caption\":\"ALBA PCB\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/es\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/albapcb_com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite - ALBA PCB Group","description":"En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/albapcb.com\/es\/microtaladrado\/","og_locale":"es_ES","og_type":"article","og_title":"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite - ALBA PCB Group","og_description":"En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12","og_url":"https:\/\/albapcb.com\/es\/microtaladrado\/","og_site_name":"ALBA PCB Group","article_published_time":"2023-10-21T07:25:08+00:00","article_modified_time":"2023-10-24T07:01:31+00:00","og_image":[{"width":1108,"height":579,"url":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/Pluritec-EVO2s-social.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@albapcb_com","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/albapcb.com\/es\/microtaladrado\/#article","isPartOf":{"@id":"https:\/\/albapcb.com\/es\/microtaladrado\/"},"author":{"name":"admin","@id":"https:\/\/albapcb.com\/es\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df"},"headline":"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite","datePublished":"2023-10-21T07:25:08+00:00","dateModified":"2023-10-24T07:01:31+00:00","mainEntityOfPage":{"@id":"https:\/\/albapcb.com\/es\/microtaladrado\/"},"wordCount":257,"publisher":{"@id":"https:\/\/albapcb.com\/es\/#organization"},"image":{"@id":"https:\/\/albapcb.com\/es\/microtaladrado\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/albapcb.com\/es\/microtaladrado\/","url":"https:\/\/albapcb.com\/es\/microtaladrado\/","name":"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite - ALBA PCB Group","isPartOf":{"@id":"https:\/\/albapcb.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/albapcb.com\/es\/microtaladrado\/#primaryimage"},"image":{"@id":"https:\/\/albapcb.com\/es\/microtaladrado\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","datePublished":"2023-10-21T07:25:08+00:00","dateModified":"2023-10-24T07:01:31+00:00","description":"En nuestro departamento de taladrado, estamos a la vanguardia de la tecnolog\u00eda de producci\u00f3n: una nueva estaci\u00f3n Pluritec EVO2s se suma a las 12","breadcrumb":{"@id":"https:\/\/albapcb.com\/es\/microtaladrado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/albapcb.com\/es\/microtaladrado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/albapcb.com\/es\/microtaladrado\/#primaryimage","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","width":1000,"height":667,"caption":"Microforatura"},{"@type":"BreadcrumbList","@id":"https:\/\/albapcb.com\/es\/microtaladrado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/albapcb.com\/es\/"},{"@type":"ListItem","position":2,"name":"Microtaladrado: velocidad y precisi\u00f3n al l\u00edmite"}]},{"@type":"WebSite","@id":"https:\/\/albapcb.com\/es\/#website","url":"https:\/\/albapcb.com\/es\/","name":"ALBA PCB Group","description":"Produttori di circuiti stampati di qualit\u00e0","publisher":{"@id":"https:\/\/albapcb.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/albapcb.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/albapcb.com\/es\/#organization","name":"ALBA PCB","url":"https:\/\/albapcb.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/albapcb.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","width":200,"height":229,"caption":"ALBA PCB"},"image":{"@id":"https:\/\/albapcb.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/albapcb.com\/es\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/x.com\/albapcb_com"]}]}},"_links":{"self":[{"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/posts\/10508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/comments?post=10508"}],"version-history":[{"count":2,"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/posts\/10508\/revisions"}],"predecessor-version":[{"id":10588,"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/posts\/10508\/revisions\/10588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/media\/10561"}],"wp:attachment":[{"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/media?parent=10508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/categories?post=10508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/albapcb.com\/es\/wp-json\/wp\/v2\/tags?post=10508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}