{"id":10490,"date":"2023-10-21T09:23:04","date_gmt":"2023-10-21T07:23:04","guid":{"rendered":"https:\/\/albapcb.com\/?p=10490"},"modified":"2023-10-21T09:30:57","modified_gmt":"2023-10-21T07:30:57","slug":"microforatura","status":"publish","type":"post","link":"https:\/\/albapcb.com\/it\/microforatura\/","title":{"rendered":"Microforatura: velocit\u00e0 e precisione spinte al massimo"},"content":{"rendered":"<p>Nel nostro reparto di foratura, siamo all&#8217;avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici automatiche gi\u00e0 in forza.<\/p>\n<p>La nostra costante scelta di innovazione ci consente di garantire prestazioni eccezionali per soddisfare le crescenti richieste di circuiti multistrato sempre pi\u00f9 complessi, sofisticati e miniaturizzati.<br \/>\nPluritec EVO2s gestisce in modo automatizzato l&#8217;intero processo, dalla fase di caricamento del pannello, con riconoscimento tramite codice a barre e gestione autonoma del programma di foratura, fino allo scarico finale, tutto ad altissima velocit\u00e0. Utilizza tre assi indipendenti con motori lineari altamente stabili e due elettro mandrini studiati per avere il miglior risultato in base al tipo di foratura:<br \/>\n\u2022 uno dedicato alla microforatura che raggiunge i 200.000 giri al minuto.<br \/>\n\u2022 uno specifico per le forature di grande diametro per una velocit\u00e0 massima di 60.000 giri al minuto.I<\/p>\n<p>l ciclo di lavoro \u00e8 caratterizzato da un&#8217;elevata precisione: sistema ottico per ottimizzazione della centratura della foratura anche nei pcb multilayer, controllo laser del diametro della punta, regolazione della profondit\u00e0 dell&#8217;asse Z.<br \/>\nTutto ci\u00f2 con limiti produttivi spinti al massimo:<br \/>\n\u2022 Microforature fino a 0,1 mm.<br \/>\n\u2022 Forature con una tolleranza controllata di +\/-15 micron.<\/p>\n<p>In sintesi, offriamo forature a velocit\u00e0 superiore e risultati perfetti per garantire ai nostri clienti la massima qualit\u00e0 e un servizio estremamente rapido.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel nostro reparto di foratura, siamo all&#8217;avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici automatiche gi\u00e0 in forza. La nostra costante scelta di innovazione ci consente di garantire prestazioni eccezionali per soddisfare le crescenti richieste di circuiti multistrato sempre pi\u00f9 complessi, sofisticati e miniaturizzati. Pluritec EVO2s gestisce in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10564,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microforatura: velocit\u00e0 e precisione spinte al massimo - ALBA PCB Group<\/title>\n<meta name=\"description\" content=\"Nel nostro reparto di foratura, siamo all&#039;avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/albapcb.com\/it\/microforatura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microforatura: velocit\u00e0 e precisione spinte al massimo - ALBA PCB Group\" \/>\n<meta property=\"og:description\" content=\"Nel nostro reparto di foratura, siamo all&#039;avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici\" \/>\n<meta property=\"og:url\" content=\"https:\/\/albapcb.com\/it\/microforatura\/\" \/>\n<meta property=\"og:site_name\" content=\"ALBA PCB Group\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-21T07:23:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-21T07:30:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/Pluritec-EVO2s-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1108\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@albapcb_com\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\"},\"headline\":\"Microforatura: velocit\u00e0 e precisione spinte al massimo\",\"datePublished\":\"2023-10-21T07:23:04+00:00\",\"dateModified\":\"2023-10-21T07:30:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/\",\"name\":\"Microforatura: velocit\u00e0 e precisione spinte al massimo - ALBA PCB Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"datePublished\":\"2023-10-21T07:23:04+00:00\",\"dateModified\":\"2023-10-21T07:30:57+00:00\",\"description\":\"Nel nostro reparto di foratura, siamo all'avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/microforatura-post.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Microforatura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/microforatura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microforatura: velocit\u00e0 e precisione spinte al massimo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\",\"name\":\"ALBA PCB Group\",\"description\":\"Produttori di circuiti stampati di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/albapcb.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\",\"name\":\"ALBA PCB\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"width\":200,\"height\":229,\"caption\":\"ALBA PCB\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/albapcb_com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microforatura: velocit\u00e0 e precisione spinte al massimo - ALBA PCB Group","description":"Nel nostro reparto di foratura, siamo all'avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/albapcb.com\/it\/microforatura\/","og_locale":"it_IT","og_type":"article","og_title":"Microforatura: velocit\u00e0 e precisione spinte al massimo - ALBA PCB Group","og_description":"Nel nostro reparto di foratura, siamo all'avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici","og_url":"https:\/\/albapcb.com\/it\/microforatura\/","og_site_name":"ALBA PCB Group","article_published_time":"2023-10-21T07:23:04+00:00","article_modified_time":"2023-10-21T07:30:57+00:00","og_image":[{"width":1108,"height":579,"url":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/Pluritec-EVO2s-social.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@albapcb_com","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/albapcb.com\/it\/microforatura\/#article","isPartOf":{"@id":"https:\/\/albapcb.com\/it\/microforatura\/"},"author":{"name":"admin","@id":"https:\/\/albapcb.com\/it\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df"},"headline":"Microforatura: velocit\u00e0 e precisione spinte al massimo","datePublished":"2023-10-21T07:23:04+00:00","dateModified":"2023-10-21T07:30:57+00:00","mainEntityOfPage":{"@id":"https:\/\/albapcb.com\/it\/microforatura\/"},"wordCount":225,"publisher":{"@id":"https:\/\/albapcb.com\/it\/#organization"},"image":{"@id":"https:\/\/albapcb.com\/it\/microforatura\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/albapcb.com\/it\/microforatura\/","url":"https:\/\/albapcb.com\/it\/microforatura\/","name":"Microforatura: velocit\u00e0 e precisione spinte al massimo - ALBA PCB Group","isPartOf":{"@id":"https:\/\/albapcb.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/albapcb.com\/it\/microforatura\/#primaryimage"},"image":{"@id":"https:\/\/albapcb.com\/it\/microforatura\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","datePublished":"2023-10-21T07:23:04+00:00","dateModified":"2023-10-21T07:30:57+00:00","description":"Nel nostro reparto di foratura, siamo all'avanguardia della tecnologia produttiva: una nuova stazione EVO2s di Pluritec si aggiunge alle 12 foratrici","breadcrumb":{"@id":"https:\/\/albapcb.com\/it\/microforatura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/albapcb.com\/it\/microforatura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/albapcb.com\/it\/microforatura\/#primaryimage","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2023\/10\/microforatura-post.jpg","width":1000,"height":667,"caption":"Microforatura"},{"@type":"BreadcrumbList","@id":"https:\/\/albapcb.com\/it\/microforatura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/albapcb.com\/it\/"},{"@type":"ListItem","position":2,"name":"Microforatura: velocit\u00e0 e precisione spinte al massimo"}]},{"@type":"WebSite","@id":"https:\/\/albapcb.com\/it\/#website","url":"https:\/\/albapcb.com\/it\/","name":"ALBA PCB Group","description":"Produttori di circuiti stampati di qualit\u00e0","publisher":{"@id":"https:\/\/albapcb.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/albapcb.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/albapcb.com\/it\/#organization","name":"ALBA PCB","url":"https:\/\/albapcb.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/albapcb.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","width":200,"height":229,"caption":"ALBA PCB"},"image":{"@id":"https:\/\/albapcb.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/albapcb.com\/it\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/x.com\/albapcb_com"]}]}},"_links":{"self":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/10490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/comments?post=10490"}],"version-history":[{"count":1,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/10490\/revisions"}],"predecessor-version":[{"id":10501,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/10490\/revisions\/10501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/media\/10564"}],"wp:attachment":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/media?parent=10490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/categories?post=10490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/tags?post=10490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}