{"id":2256,"date":"2021-04-21T21:35:15","date_gmt":"2021-04-21T19:35:15","guid":{"rendered":"https:\/\/albapcb.com\/?p=2256"},"modified":"2022-02-05T00:12:59","modified_gmt":"2022-02-04T23:12:59","slug":"utilizzare-fori-ciechi-nel-pcb-evitando-criticita","status":"publish","type":"post","link":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/","title":{"rendered":"Utilizzare fori ciechi nel PCB evitando criticit\u00e0"},"content":{"rendered":"<h2 style=\"text-align: center;\">Guida all&#8217;impiego del <em>blind<\/em> via.<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>FORATURA CIECA E PARAMETRI COSTRUTTIVI<br \/>\n<\/strong><\/p>\n<p>Per foratura cieca (blind via) si intende la realizzazione di un foro metallizzato che collega elettricamente uno strato esterno di un circuito stampato con uno interno, senza attraversare l&#8217;intero spessore del PCB.<br \/>\nIl foro viene ottenuto con una foratura controllata sull\u2019asse Z e deve avere un diametro tale da garantire un ottimale riporto metallico sulle pareti.<br \/>\nCi sono 5 parametri guida da considerare nella scelta del diametro corretto del foro cieco, in modo che garantisca qualit\u00e0 e affidabilit\u00e0 nel tempo<\/p>\n<p><strong>\/5\/ PARAMETRI DA CONSIDERARE NELL&#8217;IMPIEGO DEL FORO CIECO<\/strong><\/p>\n<p>Durante la progettazione del PCB per evitare criticit\u00e0 e avere garanzia di durata nel tempo:<br \/>\n1. Il diametro del foro.<br \/>\n2. La dimensione delle piazzole di rame connesse al foro cieco.<br \/>\n3. Lo spessore di isolamento fra i layers connessi dal foro cieco e lo spessore dei lati rame stessi.<br \/>\n4. La conseguente Aspect Ratio del foro.<br \/>\n5. Lo spessore di isolamento dal lato sottostante non connesso al foro (solo per i fori meccanici).<\/p>\n<p><strong><br \/>\n1 &#8211; DIAMETRO DEL FORO<\/strong><\/p>\n<p>Il foro pu\u00f2 essere realizzato con lavorazione meccanica o laser:<\/p>\n<p><em>FORO MECCANICO<\/em> &#8211; esso pu\u00f2 essere realizzato con un utensile di diametro minimo 0,15 mm (con tolleranza negativa ammessa di 50 \u00b5m) cos\u00ec di ottenere dopo la realizzazione dei riporti metallici al suo interno un foro di diametro di 0,05 mm (o qualche centesimo superiore).<\/p>\n<p><em>FORO LASER<\/em> &#8211; esso ha un diametro tipico di 0,1 mm all\u2019atto della realizzazione (privo di tolleranza negativa) cos\u00ec di ottenere un foro di diametro a 0,05 mm (o qualche centesimo inferiore).<\/p>\n<p><em>Nota: la metallizzazione di un foro cieco deve essere minimo 12 \u00b5m come previsto dallo standard IPC.<\/em><\/p>\n<p><strong><br \/>\n2- DIMENSIONE DELLE PIAZZOLE DI RAME CONNESSE AL FORO CIECO<\/strong><\/p>\n<p>La piazzola interessata dal foro cieco, per rispettare lo STD IPC e garantire cos\u00ec la produzione di un PCB ottimale, deve avere un diametro di dimensione almeno 300 \u00b5m (11.8mls) maggiore del diametro del foro cieco (considerando dei layers con spessore di rame di 35 \u00b5m).<br \/>\nQuesto aspetto, per quanto banale, \u00e8 molto importante per permettere una buona centratura del foro sulle piazzole stesse mantenendo la dimensione del foro richiesta. Per la foratura laser tale valore pu\u00f2 essere ridotto a 250 \u00b5m (10 mls).<\/p>\n<p><strong><br \/>\n3- SPESSORE DI ISOLAMENTO FRA I 2 LAYER CONNESSI DAL FORO CIECO<\/strong><\/p>\n<p>Come per qualsiasi PCB gli spessori degli isolanti e dei layers conduttivi dipendono dalle esigenze di progettazione elettrica e ci\u00f2 vale anche per i layers coinvolti nelle forature cieche. (collegato al Aspect Ratio)<\/p>\n<p><strong><br \/>\n4- ASPECT RATIO (AR)<\/strong><\/p>\n<p>L\u2019 Aspect Ratio \u00e8 il rapporto tra la profondit\u00e0 del foro cieco (data dallo spessore del dielettrico presente fra i 2 layers connessi dal foro, sommato allo spessore di rame dei layers stessi) e la dimensione del diametro del foro stesso.<br \/>\nLa sua importanza deriva dai limiti chimico-fisici e fluidodinamici del processo elettrolitico di placcatura (metallizzazione) dei fori; nel processo di riporto galvanico diversi liquidi devono fluire in modo efficiente all\u2019interno del cilindro ottenuto nel materiale di base dalla foratura (nonostante sia occluso da una parte) per ottenere un rivestimento metallico della parete del foro che sia robusto e con esso una connessione elettrica affidabile.<br \/>\nDetto rapporto deve essere al massimo di 1,4:1 calcolato considerando il diametro del foro a fine processo (cio\u00e8 dopo aver realizzato l\u2019apporto metallico all\u2019interno del foro).<br \/>\nCi\u00f2 significa che nel costruire il build-up del pcb bisogna tener conto che lo spessore totale del materiale (dielettrico + lati rame coinvolti) attraversato dal foro dovr\u00e0 essere solo poco superiore al diametro del foro atteso. In ottica inversa si dovr\u00e0 dimensionare il diametro di fori e piazzole in conseguenza degli spessori di dielettrico e dei lati rame prescelti.<\/p>\n<p><strong><br \/>\n5- SPESSORE DI ISOLAMENTO SOTTOSTANTE IL FORO (solo per fori meccanici)<\/strong><\/p>\n<p>\u00c8 lo spessore del dielettrico presente fra il secondo lato connesso al foro cieco e il lato interno a lui adiacente (sottostante) e non connesso. Date le tolleranze richieste dal processo di foratura controllata in asse Z e la forma dell\u2019utensile utilizzato, tale spessore deve garantire il corretto isolamento elettrico a fine lavorazione.<\/p>\n<p><strong><br \/>\n<\/strong><strong>ESEMPIO DI REALIZZAZIONE AFFIDABILE<\/strong><\/p>\n<p>su un pcb con lati rame di spessore 35um, ove il lato top e il primo lato interno sono isolati da 100um di materiale dielettrico e il secondo lato interno \u00e8 a sua volta isolato da ulteriori 150um (<strong>E<\/strong>) di materiale, si pu\u00f2 ingegnerizzare un foro cieco di diametro 150um (<strong>C<\/strong>) (non laser) centrato su piazzole circolari di diametro 450um (<strong>A<\/strong>). Tale foro viene realizzato con un utensile di diametro 250um (<strong>B<\/strong>), il quale, attraversando uno spessore di materiale (FR4 + lati rame) pari a 170um (<strong>D<\/strong>), porta ad un AR 1,13:1 (<strong>D\/C<\/strong>), che essendo inferiore a 1,4:1 garantisce un\u2019ottima realizzazione (lo spessore di materiale interessato dal foro cieco \u00e8 appena maggiore del diametro del foro stesso).<\/p>\n<p><strong>Tabella esempi di minima realizzazione:<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2359 size-full\" src=\"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/Tabella-Fori-ciechi-ITA-disegno-2-scaled.jpg\" alt=\"Fori ciechi Alba PCB\" width=\"2560\" height=\"924\" srcset=\"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/Tabella-Fori-ciechi-ITA-disegno-2-scaled.jpg 2560w, https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/Tabella-Fori-ciechi-ITA-disegno-2-300x108.jpg 300w, https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/Tabella-Fori-ciechi-ITA-disegno-2-1024x370.jpg 1024w, https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/Tabella-Fori-ciechi-ITA-disegno-2-768x277.jpg 768w, https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/Tabella-Fori-ciechi-ITA-disegno-2-1536x554.jpg 1536w, https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/Tabella-Fori-ciechi-ITA-disegno-2-2048x739.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<h3 style=\"text-align: left;\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Guida all&#8217;impiego del blind via. &nbsp; FORATURA CIECA E PARAMETRI COSTRUTTIVI Per foratura cieca (blind via) si intende la realizzazione di un foro metallizzato che collega elettricamente uno strato esterno di un circuito stampato con uno interno, senza attraversare l&#8217;intero spessore del PCB. Il foro viene ottenuto con una foratura controllata sull\u2019asse Z e deve [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2261,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Utilizzare fori ciechi nel PCB evitando criticit\u00e0 - ALBA PCB Group<\/title>\n<meta name=\"description\" content=\"Guida all&#039;impiego del blind via. &nbsp; FORATURA CIECA E PARAMETRI COSTRUTTIVI Per foratura cieca (blind via) si intende la realizzazione di un foro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utilizzare fori ciechi nel PCB evitando criticit\u00e0 - ALBA PCB Group\" \/>\n<meta property=\"og:description\" content=\"Guida all&#039;impiego del blind via. &nbsp; FORATURA CIECA E PARAMETRI COSTRUTTIVI Per foratura cieca (blind via) si intende la realizzazione di un foro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/\" \/>\n<meta property=\"og:site_name\" content=\"ALBA PCB Group\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-21T19:35:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-04T23:12:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/foro-cieco-FBIN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1196\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@albapcb_com\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\"},\"headline\":\"Utilizzare fori ciechi nel PCB evitando criticit\u00e0\",\"datePublished\":\"2021-04-21T19:35:15+00:00\",\"dateModified\":\"2022-02-04T23:12:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/\"},\"wordCount\":793,\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/foro-cieco-post.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/\",\"name\":\"Utilizzare fori ciechi nel PCB evitando criticit\u00e0 - ALBA PCB Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/foro-cieco-post.jpg\",\"datePublished\":\"2021-04-21T19:35:15+00:00\",\"dateModified\":\"2022-02-04T23:12:59+00:00\",\"description\":\"Guida all'impiego del blind via. &nbsp; FORATURA CIECA E PARAMETRI COSTRUTTIVI Per foratura cieca (blind via) si intende la realizzazione di un foro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/foro-cieco-post.jpg\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/foro-cieco-post.jpg\",\"width\":1000,\"height\":667,\"caption\":\"foro cieco pcb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Utilizzare fori ciechi nel PCB evitando criticit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\",\"name\":\"ALBA PCB Group\",\"description\":\"Produttori di circuiti stampati di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/albapcb.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\",\"name\":\"ALBA PCB\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"width\":200,\"height\":229,\"caption\":\"ALBA PCB\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/albapcb_com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Utilizzare fori ciechi nel PCB evitando criticit\u00e0 - ALBA PCB Group","description":"Guida all'impiego del blind via. &nbsp; FORATURA CIECA E PARAMETRI COSTRUTTIVI Per foratura cieca (blind via) si intende la realizzazione di un foro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/","og_locale":"it_IT","og_type":"article","og_title":"Utilizzare fori ciechi nel PCB evitando criticit\u00e0 - ALBA PCB Group","og_description":"Guida all'impiego del blind via. &nbsp; FORATURA CIECA E PARAMETRI COSTRUTTIVI Per foratura cieca (blind via) si intende la realizzazione di un foro","og_url":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/","og_site_name":"ALBA PCB Group","article_published_time":"2021-04-21T19:35:15+00:00","article_modified_time":"2022-02-04T23:12:59+00:00","og_image":[{"width":1196,"height":625,"url":"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/foro-cieco-FBIN.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@albapcb_com","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/#article","isPartOf":{"@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/"},"author":{"name":"admin","@id":"https:\/\/albapcb.com\/it\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df"},"headline":"Utilizzare fori ciechi nel PCB evitando criticit\u00e0","datePublished":"2021-04-21T19:35:15+00:00","dateModified":"2022-02-04T23:12:59+00:00","mainEntityOfPage":{"@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/"},"wordCount":793,"publisher":{"@id":"https:\/\/albapcb.com\/it\/#organization"},"image":{"@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/foro-cieco-post.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/","url":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/","name":"Utilizzare fori ciechi nel PCB evitando criticit\u00e0 - ALBA PCB Group","isPartOf":{"@id":"https:\/\/albapcb.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/#primaryimage"},"image":{"@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/foro-cieco-post.jpg","datePublished":"2021-04-21T19:35:15+00:00","dateModified":"2022-02-04T23:12:59+00:00","description":"Guida all'impiego del blind via. &nbsp; FORATURA CIECA E PARAMETRI COSTRUTTIVI Per foratura cieca (blind via) si intende la realizzazione di un foro","breadcrumb":{"@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/#primaryimage","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/foro-cieco-post.jpg","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2021\/03\/foro-cieco-post.jpg","width":1000,"height":667,"caption":"foro cieco pcb"},{"@type":"BreadcrumbList","@id":"https:\/\/albapcb.com\/it\/utilizzare-fori-ciechi-nel-pcb-evitando-criticita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/albapcb.com\/it\/"},{"@type":"ListItem","position":2,"name":"Utilizzare fori ciechi nel PCB evitando criticit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/albapcb.com\/it\/#website","url":"https:\/\/albapcb.com\/it\/","name":"ALBA PCB Group","description":"Produttori di circuiti stampati di qualit\u00e0","publisher":{"@id":"https:\/\/albapcb.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/albapcb.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/albapcb.com\/it\/#organization","name":"ALBA PCB","url":"https:\/\/albapcb.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/albapcb.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","width":200,"height":229,"caption":"ALBA PCB"},"image":{"@id":"https:\/\/albapcb.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/albapcb.com\/it\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/x.com\/albapcb_com"]}]}},"_links":{"self":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/2256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/comments?post=2256"}],"version-history":[{"count":5,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/2256\/revisions"}],"predecessor-version":[{"id":3652,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/2256\/revisions\/3652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/media\/2261"}],"wp:attachment":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/media?parent=2256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/categories?post=2256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/tags?post=2256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}