{"id":4736,"date":"2022-07-05T14:21:01","date_gmt":"2022-07-05T12:21:01","guid":{"rendered":"https:\/\/albapcb.com\/?p=4736"},"modified":"2022-08-22T14:27:34","modified_gmt":"2022-08-22T12:27:34","slug":"gianluigi-schiavo-nuovo-sales-manager","status":"publish","type":"post","link":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/","title":{"rendered":"Gianluigi Schiavo nuovo Sales Manager"},"content":{"rendered":"<p>Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell&#8217;organizzazione commerciale.<br \/>\nAbbiamo deciso di inserire in azienda un professionista di lunga esperienza, altamente qualificato, e conosciuto per l&#8217;integrit\u00e0 professionale e la grande competenza nel mondo dei circuiti stampati di cui conosce dinamiche ed esigenze.<\/p>\n<p>34 anni di esperienza nel settore, Gianluigi Schiavo \u00e8 particolarmente conosciuto nel Triveneto per l&#8217;intensa attivit\u00e0 e la fitta rete di relazioni che ha saputo sviluppare.<\/p>\n<p>Convinto del bisogno di affrontare il mercato offrendo un servizio globale (dal singolo PCB online alla produzione massiva asiatica) coniugando produzione far east a produzione italiana, Gianluigi porter\u00e0 in Alba PCB Group nuove energie che saranno preziose per un gruppo che punta ad essere sempre pi\u00f9 un riferimento del PCB in Italia ed Europa.<\/p>\n<p>A Gianluigi il nostro augurio di buon lavoro e di successi sempre pi\u00f9 grandi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell&#8217;organizzazione commerciale. Abbiamo deciso di inserire in azienda un professionista di lunga esperienza, altamente qualificato, e conosciuto per l&#8217;integrit\u00e0 professionale e la grande competenza nel mondo dei circuiti stampati di cui conosce dinamiche ed esigenze. 34 anni di esperienza nel settore, Gianluigi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4676,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gianluigi Schiavo nuovo Sales Manager - ALBA PCB Group<\/title>\n<meta name=\"description\" content=\"Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell&#039;organizzazione commerciale. Abbiamo deciso di inserire in\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gianluigi Schiavo nuovo Sales Manager - ALBA PCB Group\" \/>\n<meta property=\"og:description\" content=\"Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell&#039;organizzazione commerciale. Abbiamo deciso di inserire in\" \/>\n<meta property=\"og:url\" content=\"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/\" \/>\n<meta property=\"og:site_name\" content=\"ALBA PCB Group\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-05T12:21:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-22T12:27:34+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@albapcb_com\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\"},\"headline\":\"Gianluigi Schiavo nuovo Sales Manager\",\"datePublished\":\"2022-07-05T12:21:01+00:00\",\"dateModified\":\"2022-08-22T12:27:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/\"},\"wordCount\":148,\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Gianluigi-buona-post-sito.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/\",\"name\":\"Gianluigi Schiavo nuovo Sales Manager - ALBA PCB Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Gianluigi-buona-post-sito.jpg\",\"datePublished\":\"2022-07-05T12:21:01+00:00\",\"dateModified\":\"2022-08-22T12:27:34+00:00\",\"description\":\"Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell'organizzazione commerciale. Abbiamo deciso di inserire in\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/#primaryimage\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Gianluigi-buona-post-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Gianluigi-buona-post-sito.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Gianluigi Schiavo Alba PCB Group\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/gianluigi-schiavo-nuovo-sales-manager\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gianluigi Schiavo nuovo Sales Manager\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\",\"name\":\"ALBA PCB Group\",\"description\":\"Produttori di circuiti stampati di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/albapcb.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#organization\",\"name\":\"ALBA PCB\",\"url\":\"https:\\\/\\\/albapcb.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/albapcb.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo.png\",\"width\":200,\"height\":229,\"caption\":\"ALBA PCB\"},\"image\":{\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/albapcb.com\\\/it\\\/#\\\/schema\\\/person\\\/e7adc684b2f08b79e7d1c004c7d199df\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/albapcb_com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gianluigi Schiavo nuovo Sales Manager - ALBA PCB Group","description":"Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell'organizzazione commerciale. Abbiamo deciso di inserire in","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/","og_locale":"it_IT","og_type":"article","og_title":"Gianluigi Schiavo nuovo Sales Manager - ALBA PCB Group","og_description":"Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell'organizzazione commerciale. Abbiamo deciso di inserire in","og_url":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/","og_site_name":"ALBA PCB Group","article_published_time":"2022-07-05T12:21:01+00:00","article_modified_time":"2022-08-22T12:27:34+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@albapcb_com","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/#article","isPartOf":{"@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/"},"author":{"name":"admin","@id":"https:\/\/albapcb.com\/it\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df"},"headline":"Gianluigi Schiavo nuovo Sales Manager","datePublished":"2022-07-05T12:21:01+00:00","dateModified":"2022-08-22T12:27:34+00:00","mainEntityOfPage":{"@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/"},"wordCount":148,"publisher":{"@id":"https:\/\/albapcb.com\/it\/#organization"},"image":{"@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2022\/06\/Gianluigi-buona-post-sito.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/","url":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/","name":"Gianluigi Schiavo nuovo Sales Manager - ALBA PCB Group","isPartOf":{"@id":"https:\/\/albapcb.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/#primaryimage"},"image":{"@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/#primaryimage"},"thumbnailUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2022\/06\/Gianluigi-buona-post-sito.jpg","datePublished":"2022-07-05T12:21:01+00:00","dateModified":"2022-08-22T12:27:34+00:00","description":"Continua la strategia di sviluppo commerciale di Alba PCB Group, puntando sul potenziamento dell'organizzazione commerciale. Abbiamo deciso di inserire in","breadcrumb":{"@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/#primaryimage","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2022\/06\/Gianluigi-buona-post-sito.jpg","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2022\/06\/Gianluigi-buona-post-sito.jpg","width":1000,"height":667,"caption":"Gianluigi Schiavo Alba PCB Group"},{"@type":"BreadcrumbList","@id":"https:\/\/albapcb.com\/it\/gianluigi-schiavo-nuovo-sales-manager\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/albapcb.com\/it\/"},{"@type":"ListItem","position":2,"name":"Gianluigi Schiavo nuovo Sales Manager"}]},{"@type":"WebSite","@id":"https:\/\/albapcb.com\/it\/#website","url":"https:\/\/albapcb.com\/it\/","name":"ALBA PCB Group","description":"Produttori di circuiti stampati di qualit\u00e0","publisher":{"@id":"https:\/\/albapcb.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/albapcb.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/albapcb.com\/it\/#organization","name":"ALBA PCB","url":"https:\/\/albapcb.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/albapcb.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","contentUrl":"https:\/\/albapcb.com\/wp-content\/uploads\/2019\/10\/logo.png","width":200,"height":229,"caption":"ALBA PCB"},"image":{"@id":"https:\/\/albapcb.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/albapcb.com\/it\/#\/schema\/person\/e7adc684b2f08b79e7d1c004c7d199df","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/x.com\/albapcb_com"]}]}},"_links":{"self":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/4736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/comments?post=4736"}],"version-history":[{"count":2,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/4736\/revisions"}],"predecessor-version":[{"id":4738,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/posts\/4736\/revisions\/4738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/media\/4676"}],"wp:attachment":[{"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/media?parent=4736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/categories?post=4736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/albapcb.com\/it\/wp-json\/wp\/v2\/tags?post=4736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}